{"id":7,"count":7,"description":"","link":"https:\/\/www.steminnature.online\/lt\/category\/lithuania\/","name":"Lietuva","slug":"lithuania","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.steminnature.online\/lt\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steminnature.online\/lt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.steminnature.online\/lt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.steminnature.online\/lt\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}